{"id":1144,"date":"2026-06-15T12:43:22","date_gmt":"2026-06-15T12:43:22","guid":{"rendered":"https:\/\/analyzingmarket.com\/coins\/zcash-2\/"},"modified":"2026-06-15T12:43:22","modified_gmt":"2026-06-15T12:43:22","slug":"zcash","status":"publish","type":"coin","link":"https:\/\/analyzingmarket.com\/de\/coins\/zcash\/","title":{"rendered":"Zcash (ZEC)"},"content":{"rendered":"<p><strong>Zcash (ZEC)<\/strong> ist eine Kryptow\u00e4hrung, die nach Marktkapitalisierung auf Platz #14 rangiert, mit einem zirkulierenden Angebot von 16.768.513 ZEC von einem maximalen Angebot von 21.000.000 ZEC.<\/p>\n<p>Die unten stehenden Live-Daten werden kontinuierlich aus \u00f6ffentlichen Marktquellen aktualisiert. Diese Zahlen dienen ausschlie\u00dflich zu Informationszwecken und stellen keine Finanzberatung dar.<\/p>\n<h2>Wichtige Fakten<\/h2>\n<ul>\n<li>Rang nach Marktkapitalisierung: #14<\/li>\n<li>Zirkulierendes Angebot: 16.768.513 ZEC<\/li>\n<li>Maximales Angebot: 21.000.000 ZEC<\/li>\n<li>Allzeithoch: 3.191,93 $ (erreicht am 29. Oktober 2016)<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Zcash (ZEC) Live-Kurs, Marktkapitalisierung, Angebot und wichtige Statistiken.<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","meta":{"_am_cg_id":"zcash","_am_symbol":"ZEC","_am_rank":15,"_am_category":"","_am_genesis_year":0},"coin_category":[48,42,74,58,65,91,44,92],"class_list":["post-1144","coin","type-coin","status-publish","hentry","coin_category-coinbase-50-index","coin_category-layer-1-l1","coin_category-made-in-usa","coin_category-near-protocol-ecosystem","coin_category-pantera-capital-portfolio","coin_category-privacy-coins","coin_category-proof-of-work-pow","coin_category-zero-knowledge-zk"],"_links":{"self":[{"href":"https:\/\/analyzingmarket.com\/de\/wp-json\/wp\/v2\/coin\/1144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/analyzingmarket.com\/de\/wp-json\/wp\/v2\/coin"}],"about":[{"href":"https:\/\/analyzingmarket.com\/de\/wp-json\/wp\/v2\/types\/coin"}],"wp:attachment":[{"href":"https:\/\/analyzingmarket.com\/de\/wp-json\/wp\/v2\/media?parent=1144"}],"wp:term":[{"taxonomy":"coin_category","embeddable":true,"href":"https:\/\/analyzingmarket.com\/de\/wp-json\/wp\/v2\/coin_category?post=1144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}