{"id":1034,"date":"2026-06-15T14:38:56","date_gmt":"2026-06-15T14:38:56","guid":{"rendered":"https:\/\/analyzingmarket.com\/coins\/stable-2-2\/"},"modified":"2026-06-15T14:38:56","modified_gmt":"2026-06-15T14:38:56","slug":"stable-2","status":"publish","type":"coin","link":"https:\/\/analyzingmarket.com\/es\/coins\/stable-2\/","title":{"rendered":"\u200b\u200bStable (STABLE)"},"content":{"rendered":"<p><strong>\u200b\u200bStable (STABLE)<\/strong> es una criptomoneda clasificada en el puesto #79 por capitalizaci\u00f3n de mercado, con un suministro en circulaci\u00f3n de 23,617,903,978 STABLE.<\/p>\n<p>Los datos en vivo que se muestran a continuaci\u00f3n se actualizan continuamente a partir de fuentes p\u00fablicas del mercado. Estas cifras se proporcionan \u00fanicamente con fines informativos y no constituyen asesoramiento financiero.<\/p>\n<h2>Datos clave<\/h2>\n<ul>\n<li>Clasificaci\u00f3n por capitalizaci\u00f3n de mercado: #79<\/li>\n<li>Suministro en circulaci\u00f3n: 23,617,903,978 STABLE<\/li>\n<li>M\u00e1ximo hist\u00f3rico: $0.042672 (alcanzado el 14 de mayo de 2026)<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u200b\u200bStable (STABLE) precio en vivo, capitalizaci\u00f3n de mercado, suministro y estad\u00edsticas clave.<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","meta":{"_am_cg_id":"stable-2","_am_symbol":"STABLE","_am_rank":74,"_am_category":"","_am_genesis_year":0},"coin_category":[62,117,42,169,41,170],"class_list":["post-1034","coin","type-coin","status-publish","hentry","coin_category-bnb-chain-ecosystem","coin_category-infrastructure","coin_category-layer-1-l1","coin_category-payment-solutions","coin_category-smart-contract-platform","coin_category-stable-ecosystem"],"_links":{"self":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/coin\/1034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/coin"}],"about":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/types\/coin"}],"wp:attachment":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/media?parent=1034"}],"wp:term":[{"taxonomy":"coin_category","embeddable":true,"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/coin_category?post=1034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}