{"id":1038,"date":"2026-06-15T14:38:56","date_gmt":"2026-06-15T14:38:56","guid":{"rendered":"https:\/\/analyzingmarket.com\/coins\/polygon-ecosystem-token-2\/"},"modified":"2026-06-15T14:38:56","modified_gmt":"2026-06-15T14:38:56","slug":"polygon-ecosystem-token","status":"publish","type":"coin","link":"https:\/\/analyzingmarket.com\/es\/coins\/polygon-ecosystem-token\/","title":{"rendered":"POL (ex-MATIC) (POL)"},"content":{"rendered":"<p><strong>POL (ex-MATIC) (POL)<\/strong> es una criptomoneda clasificada en el puesto #80 por capitalizaci\u00f3n de mercado, con un suministro en circulaci\u00f3n de 10,661,337,885 POL.<\/p>\n<p>Los datos en vivo que se muestran a continuaci\u00f3n se actualizan continuamente a partir de fuentes p\u00fablicas del mercado. Estas cifras se proporcionan \u00fanicamente con fines informativos y no constituyen asesoramiento financiero.<\/p>\n<h2>Datos clave<\/h2>\n<ul>\n<li>Clasificaci\u00f3n por capitalizaci\u00f3n de mercado: #80<\/li>\n<li>Suministro en circulaci\u00f3n: 10,661,337,885 POL<\/li>\n<li>M\u00e1ximo hist\u00f3rico: $1.29 (alcanzado el 13 de marzo de 2024)<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>POL (ex-MATIC) (POL) precio en vivo, capitalizaci\u00f3n de mercado, suministro y estad\u00edsticas clave.<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","meta":{"_am_cg_id":"polygon-ecosystem-token","_am_symbol":"POL","_am_rank":74,"_am_category":"","_am_genesis_year":0},"coin_category":[49,144,68,41,92],"class_list":["post-1038","coin","type-coin","status-publish","hentry","coin_category-ethereum-ecosystem","coin_category-layer-2-l2","coin_category-polygon-ecosystem","coin_category-smart-contract-platform","coin_category-zero-knowledge-zk"],"_links":{"self":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/coin\/1038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/coin"}],"about":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/types\/coin"}],"wp:attachment":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/media?parent=1038"}],"wp:term":[{"taxonomy":"coin_category","embeddable":true,"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/coin_category?post=1038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}