{"id":1138,"date":"2026-06-15T16:53:58","date_gmt":"2026-06-15T16:53:58","guid":{"rendered":"https:\/\/analyzingmarket.com\/coins\/usual-usd-2\/"},"modified":"2026-06-15T16:53:58","modified_gmt":"2026-06-15T16:53:58","slug":"usual-usd","status":"publish","type":"coin","link":"https:\/\/analyzingmarket.com\/es\/coins\/usual-usd\/","title":{"rendered":"Usual USD (USD0)"},"content":{"rendered":"<p><strong>Usual USD (USD0)<\/strong> es una criptomoneda clasificada en el puesto #100 por capitalizaci\u00f3n de mercado, con un suministro en circulaci\u00f3n de 553,578,360 USD0.<\/p>\n<p>Los datos en vivo que se muestran a continuaci\u00f3n se actualizan continuamente a partir de fuentes p\u00fablicas del mercado. Estas cifras se proporcionan \u00fanicamente con fines informativos y no constituyen asesoramiento financiero.<\/p>\n<h2>Datos clave<\/h2>\n<ul>\n<li>Clasificaci\u00f3n por capitalizaci\u00f3n de mercado: #100<\/li>\n<li>Suministro en circulaci\u00f3n: 553,578,360 USD0<\/li>\n<li>M\u00e1ximo hist\u00f3rico: $1.33 (alcanzado el 12 de julio de 2024)<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Usual USD (USD0): precio en vivo, capitalizaci\u00f3n de mercado, suministro y estad\u00edsticas clave.<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","meta":{"_am_cg_id":"usual-usd","_am_symbol":"USD0","_am_rank":97,"_am_category":"","_am_genesis_year":0},"coin_category":[],"class_list":["post-1138","coin","type-coin","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/coin\/1138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/coin"}],"about":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/types\/coin"}],"wp:attachment":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/media?parent=1138"}],"wp:term":[{"taxonomy":"coin_category","embeddable":true,"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/coin_category?post=1138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}