{"id":1178,"date":"2026-06-15T12:43:23","date_gmt":"2026-06-15T12:43:23","guid":{"rendered":"https:\/\/analyzingmarket.com\/coins\/the-open-network-2\/"},"modified":"2026-06-15T12:43:23","modified_gmt":"2026-06-15T12:43:23","slug":"the-open-network","status":"publish","type":"coin","link":"https:\/\/analyzingmarket.com\/es\/coins\/the-open-network\/","title":{"rendered":"Gram (prev. Toncoin) (GRAM)"},"content":{"rendered":"<p><strong>Gram (prev. Toncoin) (GRAM)<\/strong> es una criptomoneda clasificada en el puesto #22 por capitalizaci\u00f3n de mercado, con un suministro circulante de 2.679.871.467 GRAM.<\/p>\n<p>Los datos en vivo que se muestran a continuaci\u00f3n se actualizan continuamente a partir de fuentes p\u00fablicas del mercado. Estas cifras se proporcionan \u00fanicamente con fines informativos y no constituyen asesoramiento financiero.<\/p>\n<h2>Datos clave<\/h2>\n<ul>\n<li>Posici\u00f3n por capitalizaci\u00f3n de mercado: #22<\/li>\n<li>Suministro circulante: 2.679.871.467 GRAM<\/li>\n<li>M\u00e1ximo hist\u00f3rico: $8,25 (alcanzado el 15 de junio de 2024)<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Gram (prev. Toncoin) (GRAM) precio en vivo, capitalizaci\u00f3n de mercado, suministro y estad\u00edsticas clave.<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","meta":{"_am_cg_id":"the-open-network","_am_symbol":"GRAM","_am_rank":24,"_am_category":"","_am_genesis_year":0},"coin_category":[],"class_list":["post-1178","coin","type-coin","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/coin\/1178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/coin"}],"about":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/types\/coin"}],"wp:attachment":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/media?parent=1178"}],"wp:term":[{"taxonomy":"coin_category","embeddable":true,"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/coin_category?post=1178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}