{"id":1254,"date":"2026-06-20T16:52:05","date_gmt":"2026-06-20T16:52:05","guid":{"rendered":"https:\/\/analyzingmarket.com\/coins\/aerodrome-finance-2\/"},"modified":"2026-06-20T16:52:05","modified_gmt":"2026-06-20T16:52:05","slug":"aerodrome-finance","status":"publish","type":"coin","link":"https:\/\/analyzingmarket.com\/es\/coins\/aerodrome-finance\/","title":{"rendered":"Aerodrome Finance (AERO)"},"content":{"rendered":"<p><strong>Aerodrome Finance (AERO)<\/strong> es una criptomoneda clasificada en el puesto #104 por capitalizaci\u00f3n de mercado, con un suministro en circulaci\u00f3n de 956,775,952 AERO.<\/p>\n<p>Los datos en vivo que se muestran a continuaci\u00f3n se actualizan continuamente a partir de fuentes p\u00fablicas del mercado. Estas cifras se proporcionan \u00fanicamente con fines informativos y no constituyen asesoramiento financiero.<\/p>\n<h2>Datos clave<\/h2>\n<ul>\n<li>Clasificaci\u00f3n por capitalizaci\u00f3n de mercado: #104<\/li>\n<li>Suministro en circulaci\u00f3n: 956,775,952 AERO<\/li>\n<li>M\u00e1ximo hist\u00f3rico: $2.32 (alcanzado el 7 de diciembre de 2024)<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Aerodrome Finance (AERO): precio en vivo, capitalizaci\u00f3n de mercado, suministro y estad\u00edsticas clave.<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","meta":{"_am_cg_id":"aerodrome-finance","_am_symbol":"AERO","_am_rank":98,"_am_category":"","_am_genesis_year":0},"coin_category":[],"class_list":["post-1254","coin","type-coin","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/coin\/1254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/coin"}],"about":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/types\/coin"}],"wp:attachment":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/media?parent=1254"}],"wp:term":[{"taxonomy":"coin_category","embeddable":true,"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/coin_category?post=1254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}