{"id":1406,"date":"2026-06-15T12:43:23","date_gmt":"2026-06-15T12:43:23","guid":{"rendered":"https:\/\/analyzingmarket.com\/coins\/eutbl-2\/"},"modified":"2026-06-15T12:43:23","modified_gmt":"2026-06-15T12:43:23","slug":"eutbl","status":"publish","type":"coin","link":"https:\/\/analyzingmarket.com\/es\/coins\/eutbl\/","title":{"rendered":"Spiko EU T-Bills Money Market Fund (EUTBL)"},"content":{"rendered":"<p><strong>Spiko EU T-Bills Money Market Fund (EUTBL)<\/strong> es una criptomoneda clasificada en el puesto #70 por capitalizaci\u00f3n de mercado, con un suministro circulante de 797,351,591 EUTBL.<\/p>\n<p>Los datos en vivo que se muestran a continuaci\u00f3n se actualizan continuamente a partir de fuentes p\u00fablicas del mercado. Estas cifras se proporcionan \u00fanicamente con fines informativos y no constituyen asesoramiento financiero.<\/p>\n<h2>Datos clave<\/h2>\n<ul>\n<li>Posici\u00f3n por capitalizaci\u00f3n de mercado: #70<\/li>\n<li>Suministro circulante: 797,351,591 EUTBL<\/li>\n<li>M\u00e1ximo hist\u00f3rico: $1.26 (alcanzado el 27 de enero de 2026)<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Spiko EU T-Bills Money Market Fund (EUTBL): precio en vivo, capitalizaci\u00f3n de mercado, suministro y estad\u00edsticas clave.<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","meta":{"_am_cg_id":"eutbl","_am_symbol":"EUTBL","_am_rank":65,"_am_category":"","_am_genesis_year":0},"coin_category":[69,102,49,68,73,131,93,122],"class_list":["post-1406","coin","type-coin","status-publish","hentry","coin_category-arbitrum-ecosystem","coin_category-base-ecosystem","coin_category-ethereum-ecosystem","coin_category-polygon-ecosystem","coin_category-real-world-assets-rwa","coin_category-starknet-ecosystem","coin_category-stellar-ecosystem","coin_category-tokenized-assets"],"_links":{"self":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/coin\/1406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/coin"}],"about":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/types\/coin"}],"wp:attachment":[{"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/media?parent=1406"}],"wp:term":[{"taxonomy":"coin_category","embeddable":true,"href":"https:\/\/analyzingmarket.com\/es\/wp-json\/wp\/v2\/coin_category?post=1406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}