{"id":1361,"date":"2026-06-15T12:43:23","date_gmt":"2026-06-15T12:43:23","guid":{"rendered":"https:\/\/analyzingmarket.com\/coins\/bfusd-2\/"},"modified":"2026-06-15T12:43:23","modified_gmt":"2026-06-15T12:43:23","slug":"bfusd","status":"publish","type":"coin","link":"https:\/\/analyzingmarket.com\/pt-br\/coins\/bfusd\/","title":{"rendered":"BFUSD (BFUSD)"},"content":{"rendered":"<p><strong>BFUSD (BFUSD)<\/strong> \u00e9 uma criptomoeda classificada na posi\u00e7\u00e3o #59 por capitaliza\u00e7\u00e3o de mercado, com uma oferta circulante de 1,320,000,000 BFUSD.<\/p>\n<p>Os dados ao vivo abaixo s\u00e3o atualizados continuamente a partir de fontes p\u00fablicas de mercado. Esses n\u00fameros s\u00e3o fornecidos apenas para fins informativos e n\u00e3o constituem aconselhamento financeiro.<\/p>\n<h2>Fatos principais<\/h2>\n<ul>\n<li>Classifica\u00e7\u00e3o por capitaliza\u00e7\u00e3o de mercado: #59<\/li>\n<li>Oferta circulante: 1,320,000,000 BFUSD<\/li>\n<li>M\u00e1xima hist\u00f3rica: $1.01 (alcan\u00e7ada em 10 de outubro de 2025)<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>BFUSD (BFUSD): pre\u00e7o ao vivo, capitaliza\u00e7\u00e3o de mercado, oferta e estat\u00edsticas principais.<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","meta":{"_am_cg_id":"bfusd","_am_symbol":"BFUSD","_am_rank":59,"_am_category":"","_am_genesis_year":0},"coin_category":[54,157],"class_list":["post-1361","coin","type-coin","status-publish","hentry","coin_category-stablecoins","coin_category-yield-bearing-stablecoin"],"_links":{"self":[{"href":"https:\/\/analyzingmarket.com\/pt-br\/wp-json\/wp\/v2\/coin\/1361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/analyzingmarket.com\/pt-br\/wp-json\/wp\/v2\/coin"}],"about":[{"href":"https:\/\/analyzingmarket.com\/pt-br\/wp-json\/wp\/v2\/types\/coin"}],"wp:attachment":[{"href":"https:\/\/analyzingmarket.com\/pt-br\/wp-json\/wp\/v2\/media?parent=1361"}],"wp:term":[{"taxonomy":"coin_category","embeddable":true,"href":"https:\/\/analyzingmarket.com\/pt-br\/wp-json\/wp\/v2\/coin_category?post=1361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}